{"id":245,"count":1,"description":"","link":"https:\/\/pro-webdesigns.com\/da\/tag\/target-audience\/","name":"target audience","slug":"target-audience","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/pro-webdesigns.com\/da\/wp-json\/wp\/v2\/tags\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pro-webdesigns.com\/da\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/pro-webdesigns.com\/da\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/pro-webdesigns.com\/da\/wp-json\/wp\/v2\/posts?tags=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}